{"id":59,"date":"2023-11-27T11:47:08","date_gmt":"2023-11-27T10:47:08","guid":{"rendered":"https:\/\/miaft.com\/home\/"},"modified":"2026-01-28T11:22:08","modified_gmt":"2026-01-28T10:22:08","slug":"home","status":"publish","type":"page","link":"https:\/\/miaft.com\/fr\/","title":{"rendered":"Accueil"},"content":{"rendered":"<div class=\"oi-block oi-block-hero-images\" ><div class=\"hero-container\">\n    <div class=\"image-box\">\n        <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner.jpg\" class=\"featured-image d-none d-lg-block\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner.jpg 1920w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-1199x674.jpg 1199w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>        <img decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-mobile.jpg\" class=\"featured-image d-lg-none\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-mobile.jpg 1080w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-mobile-864x1536.jpg 864w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-mobile-150x267.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-mobile-575x1022.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-mobile-767x1364.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-mobile-991x1762.jpg 991w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>    <\/div>\n    <div class=\"image-layer\"><\/div>\n    <div class=\"content-box\">\n        <div class=\"row align-items-center mx-0\">\n            <div class=\"col-12 col-lg-7\">\n                                    <h2 class=\"color-secondary text-uppercase h5 mb-3\">\n                        Mia Food tech                    <\/h2>\n                                                    <h1 class=\"h1 color-white mb-3\">\n                        Machines pour l'industrie de la confiserie                    <\/h1>\n                                                    <h4 class=\"color-white mb-0\">\n                        Engineering sweetness                    <\/h4>\n                            <\/div>\n            <div class=\"d-none d-lg-block col-12 col-lg-5\">\n                <div class=\"hero-images\">\n                    \n<div class=\"oi-block oi-block-hero-images--image\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/barrette-energetiche\/\" class=\"image-toggle\" title=\"Barres \u00e9nerg\u00e9tiques \u2014\">\n    <div class=\"d-none image-container\">\n                    <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-barrette-energetiche.jpg\" class=\"featured-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-barrette-energetiche.jpg 1920w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-barrette-energetiche-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-barrette-energetiche-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-barrette-energetiche-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-barrette-energetiche-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-barrette-energetiche-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-barrette-energetiche-1199x674.jpg 1199w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>            <\/div>\n    <div class=\"d-none link-container\">\n                    https:\/\/miaft.com\/fr\/finished-product\/barrette-energetiche\/            <\/div>\n    <h4 class=\"mb-0 color-secondary text-end image-title\">\n        Barres \u00e9nerg\u00e9tiques \u2014    <\/h4>\n<\/a><\/div>\n\n<div class=\"oi-block oi-block-hero-images--image\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/croccante\/\" class=\"image-toggle\" title=\"Nougatine \u2014\">\n    <div class=\"d-none image-container\">\n                    <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-croccante.jpg\" class=\"featured-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-croccante.jpg 1920w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-croccante-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-croccante-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-croccante-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-croccante-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-croccante-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-croccante-1199x674.jpg 1199w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>            <\/div>\n    <div class=\"d-none link-container\">\n                    https:\/\/miaft.com\/fr\/finished-product\/croccante\/            <\/div>\n    <h4 class=\"mb-0 color-secondary text-end image-title\">\n        Nougatine \u2014    <\/h4>\n<\/a><\/div>\n\n<div class=\"oi-block oi-block-hero-images--image\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/paste-e-creme-spalmabili\/\" class=\"image-toggle\" title=\"P\u00e2tes et cr\u00e8mes \u00e0 tartiner \u2014\">\n    <div class=\"d-none image-container\">\n                    <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-paste-e-creme-spamabili.jpg\" class=\"featured-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-paste-e-creme-spamabili.jpg 1920w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-paste-e-creme-spamabili-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-paste-e-creme-spamabili-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-paste-e-creme-spamabili-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-paste-e-creme-spamabili-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-paste-e-creme-spamabili-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-banner-paste-e-creme-spamabili-1199x674.jpg 1199w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>            <\/div>\n    <div class=\"d-none link-container\">\n                    https:\/\/miaft.com\/fr\/finished-product\/paste-e-creme-spalmabili\/            <\/div>\n    <h4 class=\"mb-0 color-secondary text-end image-title\">\n        P\u00e2tes et cr\u00e8mes \u00e0 tartiner \u2014    <\/h4>\n<\/a><\/div>\n\n<div class=\"oi-block oi-block-hero-images--image\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/torrone\/\" class=\"image-toggle\" title=\"Nougat \u2014\">\n    <div class=\"d-none image-container\">\n                    <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-torrone.jpg\" class=\"featured-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-torrone.jpg 1920w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-torrone-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-torrone-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-torrone-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-torrone-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-torrone-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-torrone-1199x674.jpg 1199w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>            <\/div>\n    <div class=\"d-none link-container\">\n                    https:\/\/miaft.com\/fr\/finished-product\/torrone\/            <\/div>\n    <h4 class=\"mb-0 color-secondary text-end image-title\">\n        Nougat \u2014    <\/h4>\n<\/a><\/div>\n\n<div class=\"oi-block oi-block-hero-images--image\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/cioccolato\/\" class=\"image-toggle\" title=\"Chocolat \u2014\">\n    <div class=\"d-none image-container\">\n                    <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-cioccolato.jpg\" class=\"featured-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-cioccolato.jpg 1920w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-cioccolato-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-cioccolato-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-cioccolato-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-cioccolato-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-cioccolato-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-cioccolato-1199x674.jpg 1199w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>            <\/div>\n    <div class=\"d-none link-container\">\n                    https:\/\/miaft.com\/fr\/finished-product\/cioccolato\/            <\/div>\n    <h4 class=\"mb-0 color-secondary text-end image-title\">\n        Chocolat \u2014    <\/h4>\n<\/a><\/div>\n\n<div class=\"oi-block oi-block-hero-images--image\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/pralinato-e-dragees\/\" class=\"image-toggle\" title=\"Pralin\u00e9s et drag\u00e9es  \u2014\">\n    <div class=\"d-none image-container\">\n                    <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-praline.jpg\" class=\"featured-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-praline.jpg 1920w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-praline-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-praline-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-praline-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-praline-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-praline-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-praline-1199x674.jpg 1199w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>            <\/div>\n    <div class=\"d-none link-container\">\n                    https:\/\/miaft.com\/fr\/finished-product\/pralinato-e-dragees\/            <\/div>\n    <h4 class=\"mb-0 color-secondary text-end image-title\">\n        Pralin\u00e9s et drag\u00e9es  \u2014    <\/h4>\n<\/a><\/div>\n\n<div class=\"oi-block oi-block-hero-images--image\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/frutta-secca\/\" class=\"image-toggle\" title=\"Fruits secs \u2014\">\n    <div class=\"d-none image-container\">\n                    <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-frutta-secca.jpg\" class=\"featured-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-frutta-secca.jpg 1920w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-frutta-secca-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-frutta-secca-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-frutta-secca-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-frutta-secca-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-frutta-secca-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-frutta-secca-1199x674.jpg 1199w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>            <\/div>\n    <div class=\"d-none link-container\">\n                    https:\/\/miaft.com\/fr\/finished-product\/frutta-secca\/            <\/div>\n    <h4 class=\"mb-0 color-secondary text-end image-title\">\n        Fruits secs \u2014    <\/h4>\n<\/a><\/div>\n\n<div class=\"oi-block oi-block-hero-images--image\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/attrezzatura-per-pasticceria\/\" class=\"image-toggle\" title=\"\u00c9quipement de p\u00e2tisserie \u2014\">\n    <div class=\"d-none image-container\">\n                    <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-attrezzatura-per-pasticceria.jpg\" class=\"featured-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-attrezzatura-per-pasticceria.jpg 1920w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-attrezzatura-per-pasticceria-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-attrezzatura-per-pasticceria-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-attrezzatura-per-pasticceria-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-attrezzatura-per-pasticceria-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-attrezzatura-per-pasticceria-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-attrezzatura-per-pasticceria-1199x674.jpg 1199w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>            <\/div>\n    <div class=\"d-none link-container\">\n                    https:\/\/miaft.com\/fr\/finished-product\/attrezzatura-per-pasticceria\/            <\/div>\n    <h4 class=\"mb-0 color-secondary text-end image-title\">\n        \u00c9quipement de p\u00e2tisserie \u2014    <\/h4>\n<\/a><\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n            <div class=\"btn-box\">\n            <a class=\"d-flex align-items-center color-secondary\" href=\"https:\/\/miaft.com\/fr\/tutti-i-prodotti\/\" title=\"D\u00e9couvrez les produits\">\n                <span>D\u00e9couvrez les produits<\/span>\n                <span class=\"arrow-icon\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\">\n                        <g transform=\"translate(-1344 -440)\">\n                            <path d=\"M8,0,6.545,1.455l5.506,5.506H0V9.039H12.052L6.545,14.545,8,16l8-8Z\" transform=\"translate(1344 440)\" fill=\"currentColor\" \/>\n                        <\/g>\n                    <\/svg>\n                <\/span>\n            <\/a>\n        <\/div>\n    <\/div><\/div>\n\n<div class=\"oi-block oi-block-layout-container container\" style=\"\"  >\n    <div class=\"oi-block oi-block-layout-row row  justify-content-between row-vertical-gap\">\n        \n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-6 col-xl-6 col-xxl-6\" style=\"\" >\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:60px; --oi-block-space-sm:75px; --oi-block-space-md:90px; --oi-block-space-lg:200px; --oi-block-space-xl:200px; --oi-block-space-xxl:200px\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading has-primary-color has-text-color has-link-color wp-elements-d18cba0cf5b7d51bbda97fe3941eacfb\" style=\"text-transform:uppercase\">MACHINES POUR PRODUIT FINI<\/h5>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Catalogue de production<\/strong><\/h2>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n    <div class=\"oi-block oi-block-layout-row row  \">\n        \n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-12 col-xl-10 col-xxl-10\" style=\"\" >\n\n<h4 class=\"wp-block-heading\" style=\"font-style:normal;font-weight:400\">MIA Food Tech fabrique des machines destin\u00e9es \u00e0 l'industrie alimentaire avec une attention particuli\u00e8re pour des produits tels que les compl\u00e9ments alimentaires, le chocolat, les pralines, les drag\u00e9es, le nougat, la nougatine, les confitures, les en-cas \u00e0 base de c\u00e9r\u00e9ales, de muesli et de fruits secs.<\/h4>\n\n<\/div>\n    <\/div>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n<div class=\"oi-block oi-block-collapse\" ><div class=\"collapse-main with-icon\">\n    <a class=\"collapse-toggle d-block\" data-bs-toggle=\"collapse\" href=\"#collapse-block-4659\" role=\"button\" aria-expanded=\"false\">\n                    <img decoding=\"async\" class=\"link-image\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/09\/icona-barrette.svg\" alt=\"Barres \u00e9nerg\u00e9tiques\u00a0\" \/>\n                <span class=\"link-label\">\n            Barres \u00e9nerg\u00e9tiques\u00a0        <\/span>\n    <\/a>\n    <div id=\"collapse-block-4659\" class=\"collapse \">\n        <div class=\"collapse-body\">\n            \n\n<p>Les machines MIA Food Tech permettent de r\u00e9aliser des recettes \u00e0 base de c\u00e9r\u00e9ales et de liants (graisses ou fibres) selon des processus manuels, semi-automatiques et automatiques.<\/p>\n\n\n<div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/barrette-energetiche\/\" title=\"\" class=\"btn-default btn-type-arrow \" >\n    D\u00e9couvrez            <span class=\"icon-arrow\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\">\n                <path d=\"M8,0,6.545,1.455l5.506,5.506H0V9.039H12.052L6.545,14.545,8,16l8-8Z\" fill=\"currentColor\" \/>\n            <\/svg>\n        <\/span>\n    <\/a><\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div>\n\n<div class=\"oi-block oi-block-collapse\" ><div class=\"collapse-main with-icon\">\n    <a class=\"collapse-toggle d-block\" data-bs-toggle=\"collapse\" href=\"#collapse-block-6270\" role=\"button\" aria-expanded=\"false\">\n                    <img decoding=\"async\" class=\"link-image\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/09\/icona-barrette.svg\" alt=\"Nougatine\u00a0\" \/>\n                <span class=\"link-label\">\n            Nougatine\u00a0        <\/span>\n    <\/a>\n    <div id=\"collapse-block-6270\" class=\"collapse \">\n        <div class=\"collapse-body\">\n            \n\n<p>Les machines de MIA Food Tech permettent de r\u00e9aliser de la nougatine avec des fruits secs entiers ou concass\u00e9s, du sucre et un \u00e9ventuel ajout de glucose.&nbsp;Notre gamme de machines r\u00e9duit la fatigue des op\u00e9rateurs et permet de m\u00e9caniser certaines op\u00e9rations qui sont tr\u00e8s souvent effectu\u00e9es manuellement.<\/p>\n\n\n<div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/croccante\/\" title=\"\" class=\"btn-default btn-type-arrow \" >\n    D\u00e9couvrez            <span class=\"icon-arrow\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\">\n                <path d=\"M8,0,6.545,1.455l5.506,5.506H0V9.039H12.052L6.545,14.545,8,16l8-8Z\" fill=\"currentColor\" \/>\n            <\/svg>\n        <\/span>\n    <\/a><\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div>\n\n<div class=\"oi-block oi-block-collapse\" ><div class=\"collapse-main with-icon\">\n    <a class=\"collapse-toggle d-block\" data-bs-toggle=\"collapse\" href=\"#collapse-block-3681\" role=\"button\" aria-expanded=\"false\">\n                    <img decoding=\"async\" class=\"link-image\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/09\/icona-frutta-secca.svg\" alt=\"P\u00e2tes et cr\u00e8mes \u00e0 tartiner\" \/>\n                <span class=\"link-label\">\n            P\u00e2tes et cr\u00e8mes \u00e0 tartiner        <\/span>\n    <\/a>\n    <div id=\"collapse-block-3681\" class=\"collapse \">\n        <div class=\"collapse-body\">\n            \n\n<p>MIA Food Tech propose une s\u00e9rie de machines pour la production de p\u00e2tes de fruits secs, de cr\u00e8mes \u00e0 tartiner, de chocolat, de succ\u00e9dan\u00e9s et de p\u00e2tes pour la fabrication de glaces et de p\u00e2tisseries.&nbsp;Les machines varient en taille et en capacit\u00e9, avec diff\u00e9rents solutions pour les laboratoires et les petites entreprises produisant de 15 \u00e0 120 kg par lot.<\/p>\n\n\n<div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/paste-e-creme-spalmabili\/\" title=\"\" class=\"btn-default btn-type-arrow \" >\n    D\u00e9couvrez            <span class=\"icon-arrow\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\">\n                <path d=\"M8,0,6.545,1.455l5.506,5.506H0V9.039H12.052L6.545,14.545,8,16l8-8Z\" fill=\"currentColor\" \/>\n            <\/svg>\n        <\/span>\n    <\/a><\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div>\n\n<div class=\"oi-block oi-block-collapse\" ><div class=\"collapse-main with-icon\">\n    <a class=\"collapse-toggle d-block\" data-bs-toggle=\"collapse\" href=\"#collapse-block-6384\" role=\"button\" aria-expanded=\"false\">\n                    <img decoding=\"async\" class=\"link-image\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/09\/icona-torrone.svg\" alt=\"Nougat\" \/>\n                <span class=\"link-label\">\n            Nougat        <\/span>\n    <\/a>\n    <div id=\"collapse-block-6384\" class=\"collapse \">\n        <div class=\"collapse-body\">\n            \n\n<p>Les machines MIA Food Tech permettent de r\u00e9aliser de la nougatine et du nougat selon un processus manuel, semi-automatique et automatique.&nbsp;Parmi la gamme de machines suivante, vous trouverez des machines adapt\u00e9es \u00e0 tous les types de fabrication de nougats et de nougatines, avec des technologies innovantes qui facilitent le travail des op\u00e9rateurs en r\u00e9duisant la fatigue et la dur\u00e9e des processus.<\/p>\n\n\n<div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/torrone\/\" title=\"\" class=\"btn-default btn-type-arrow \" >\n    D\u00e9couvrez            <span class=\"icon-arrow\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\">\n                <path d=\"M8,0,6.545,1.455l5.506,5.506H0V9.039H12.052L6.545,14.545,8,16l8-8Z\" fill=\"currentColor\" \/>\n            <\/svg>\n        <\/span>\n    <\/a><\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div>\n\n<div class=\"oi-block oi-block-collapse\" ><div class=\"collapse-main with-icon\">\n    <a class=\"collapse-toggle d-block\" data-bs-toggle=\"collapse\" href=\"#collapse-block-1727\" role=\"button\" aria-expanded=\"false\">\n                    <img decoding=\"async\" class=\"link-image\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/09\/icona-cioccolato.svg\" alt=\"Chocolat\" \/>\n                <span class=\"link-label\">\n            Chocolat        <\/span>\n    <\/a>\n    <div id=\"collapse-block-1727\" class=\"collapse \">\n        <div class=\"collapse-body\">\n            \n\n<p>Pour compl\u00e9ter toute la gamme de machines pour la production de nougats, nougatines, etc., MIA Food Tech a r\u00e9alis\u00e9 une s\u00e9rie d'enrobeuses\/temp\u00e9reuses munies de grilles de 400-600-800, d'une capacit\u00e9 de 50 \u00e0 200 kg\/heure de chocolat temp\u00e9r\u00e9.<\/p>\n\n\n<div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/cioccolato\/\" title=\"\" class=\"btn-default btn-type-arrow \" >\n    D\u00e9couvrez            <span class=\"icon-arrow\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\">\n                <path d=\"M8,0,6.545,1.455l5.506,5.506H0V9.039H12.052L6.545,14.545,8,16l8-8Z\" fill=\"currentColor\" \/>\n            <\/svg>\n        <\/span>\n    <\/a><\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div>\n\n<div class=\"oi-block oi-block-collapse\" ><div class=\"collapse-main with-icon\">\n    <a class=\"collapse-toggle d-block\" data-bs-toggle=\"collapse\" href=\"#collapse-block-6876\" role=\"button\" aria-expanded=\"false\">\n                    <img decoding=\"async\" class=\"link-image\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/09\/icona-frutta-secca.svg\" alt=\"Fruits secs\" \/>\n                <span class=\"link-label\">\n            Fruits secs        <\/span>\n    <\/a>\n    <div id=\"collapse-block-6876\" class=\"collapse \">\n        <div class=\"collapse-body\">\n            \n\n<p>Afin des compl\u00e9ter la gamme de machines de production de nougats, de chocolat, de nougatine, etc., MIA Food Tech a d\u00e9velopp\u00e9 une s\u00e9rie de torr\u00e9facteurs d\u2019une capacit\u00e9 de 50, 150 ou 250 kg de produit, pour la torr\u00e9faction de tous types de fruits secs, avec chargement et d\u00e9chargement automatiques, et donc faciles et pratiques \u00e0 utiliser et \u00e0 nettoyer.<\/p>\n\n\n<div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/frutta-secca\/\" title=\"\" class=\"btn-default btn-type-arrow \" >\n    D\u00e9couvrez            <span class=\"icon-arrow\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\">\n                <path d=\"M8,0,6.545,1.455l5.506,5.506H0V9.039H12.052L6.545,14.545,8,16l8-8Z\" fill=\"currentColor\" \/>\n            <\/svg>\n        <\/span>\n    <\/a><\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div>\n\n<div class=\"oi-block oi-block-collapse\" ><div class=\"collapse-main with-icon\">\n    <a class=\"collapse-toggle d-block\" data-bs-toggle=\"collapse\" href=\"#collapse-block-1482\" role=\"button\" aria-expanded=\"false\">\n                    <img decoding=\"async\" class=\"link-image\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/09\/icona-pralinati.svg\" alt=\"Pralin\u00e9s et drag\u00e9es\" \/>\n                <span class=\"link-label\">\n            Pralin\u00e9s et drag\u00e9es        <\/span>\n    <\/a>\n    <div id=\"collapse-block-1482\" class=\"collapse \">\n        <div class=\"collapse-body\">\n            \n\n<p>Cette gamme de machines automatiques ou semi-automatiques de MIA Food Tech permet de r\u00e9aliser du pralin (fruits secs enrob\u00e9s de sucre caram\u00e9lis\u00e9), des drag\u00e9es (fruits secs enrob\u00e9s de chocolat) et des \u00e9clats caram\u00e9lis\u00e9s (fruits secs concass\u00e9s enrob\u00e9s de sucre caram\u00e9lis\u00e9).<\/p>\n\n\n<div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/pralinato-e-dragees\/\" title=\"\" class=\"btn-default btn-type-arrow \" >\n    D\u00e9couvrez            <span class=\"icon-arrow\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\">\n                <path d=\"M8,0,6.545,1.455l5.506,5.506H0V9.039H12.052L6.545,14.545,8,16l8-8Z\" fill=\"currentColor\" \/>\n            <\/svg>\n        <\/span>\n    <\/a><\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div>\n\n<div class=\"oi-block oi-block-collapse\" ><div class=\"collapse-main with-icon\">\n    <a class=\"collapse-toggle d-block\" data-bs-toggle=\"collapse\" href=\"#collapse-block-2175\" role=\"button\" aria-expanded=\"false\">\n                    <img decoding=\"async\" class=\"link-image\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/09\/icona-attrezzatura.svg\" alt=\"\u00c9quipement de p\u00e2tisserie\" \/>\n                <span class=\"link-label\">\n            \u00c9quipement de p\u00e2tisserie        <\/span>\n    <\/a>\n    <div id=\"collapse-block-2175\" class=\"collapse \">\n        <div class=\"collapse-body\">\n            \n\n<p>Pour r\u00e9pondre aux besoins du secteur de la p\u00e2tisserie, des petits ateliers artisanaux ou des laboratoires de recherche et d'exp\u00e9rimentation, et fournir un \u00e9quipement adapt\u00e9 \u00e0 des productions de moindre envergure, MIA Food Tech propose une s\u00e9rie de machines de petite taille b\u00e9n\u00e9ficiant de la m\u00eame technologie que celle des installations de production.<\/p>\n\n\n<div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/finished-product\/attrezzatura-per-pasticceria\/\" title=\"\" class=\"btn-default btn-type-arrow \" >\n    D\u00e9couvrez            <span class=\"icon-arrow\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\">\n                <path d=\"M8,0,6.545,1.455l5.506,5.506H0V9.039H12.052L6.545,14.545,8,16l8-8Z\" fill=\"currentColor\" \/>\n            <\/svg>\n        <\/span>\n    <\/a><\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div>\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:60px; --oi-block-space-sm:75px; --oi-block-space-md:90px; --oi-block-space-lg:200px; --oi-block-space-xl:200px; --oi-block-space-xxl:200px\"><\/div>\n\n<\/div>\n\n<div class=\"oi-block oi-block-layout-row-column d-flex flex-column justify-content-between col-12 col-sm-12 col-md-12 col-lg-5 col-xl-5 col-xxl-5\" style=\"\" >\n\n<div class=\"wp-block-group position-relative z-3 overflowed-child is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow has-background\" style=\"border-top-left-radius:10px;border-bottom-left-radius:10px;background-image:url(&#039;https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-animazione-categorie-produzione.gif&#039;);background-position:50% 50%;background-repeat:no-repeat;background-size:contain;\">    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:400px; --oi-block-space-sm:500px; --oi-block-space-md:760px; --oi-block-space-lg:760px; --oi-block-space-xl:760px; --oi-block-space-xxl:1060px\"><\/div>\n<\/div>\n<\/div>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:60px; --oi-block-space-sm:75px; --oi-block-space-md:90px; --oi-block-space-lg:1px; --oi-block-space-xl:1px; --oi-block-space-xxl:1px\"><\/div>\n\n\n\n<div class=\"wp-block-group position-relative z-3 has-light-background-color has-background oi-anim has-custom-sizing is-layout-flow wp-block-group-is-layout-flow\" style=\"border-radius:10px;--oi-style-padding-xs:60px 40px 45px 40px;--oi-style-padding-sm:90px 50px 90px 50px;--oi-style-padding-md:90px 50px 90px 50px;--oi-style-padding-lg:90px 60px 90px 60px;--oi-style-padding-xl:90px 70px 90px 70px;--oi-style-padding-xxl:90px 90px 90px 90px;--oi-style-margin-xs:0px 0px -100px 0px;--oi-style-margin-sm:0px 0px -100px 0px;--oi-style-margin-md:0px 0px -100px 0px;--oi-style-margin-lg:0px 0px -100px 0px;--oi-style-margin-xl:0px 0px -100px 0px;--oi-style-margin-xxl:0px 0px -100px 0px\" data-oi-anim=\"fade-up\" data-oi-anim-delay=\"0.3\">\n<h4 class=\"wp-block-heading\" style=\"text-transform:uppercase\">D\u00e9couvrez le fonctionnement de nos machines<\/h4>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:15px; --oi-block-space-sm:15px; --oi-block-space-md:15px; --oi-block-space-lg:15px; --oi-block-space-xl:15px; --oi-block-space-xxl:15px\"><\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-3 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/miaft.com\/fr\/video\/\"><img decoding=\"async\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/09\/icona-play.svg\" alt=\"\" class=\"wp-image-28575\"\/><\/a><\/figure>\n\n\n\n<h6 class=\"wp-block-heading has-primary-color has-text-color wp-elements-755bd2c2a74a263ffc7f76070a351882\" style=\"text-transform:uppercase\"><a href=\"https:\/\/miaft.com\/fr\/video\/\" data-type=\"page\" data-id=\"254\">Regardez les vid\u00e9os<\/a><\/h6>\n<\/div>\n<\/div>\n\n<\/div>\n    <\/div>\n\n<\/div>\n\n\n<div style=\"background-image:url(&#039;https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-home-sfondo-tipologia-lavorazione-black-mobile.jpg&#039;);background-position:50% 100%;background-size:cover;\" class=\"wp-block-group has-white-color has-text-color is-layout-flow wp-block-group-is-layout-flow has-background\"><div class=\"oi-block oi-block-layout-container container\" style=\"\"  >\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:200px; --oi-block-space-sm:200px; --oi-block-space-md:200px; --oi-block-space-lg:200px; --oi-block-space-xl:200px; --oi-block-space-xxl:200px\"><\/div>\n\n\n    <div class=\"oi-block oi-block-layout-row row  \">\n        \n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-10 col-xl-10 col-xxl-10\" style=\"\" >\n\n<h5 class=\"wp-block-heading has-secondary-color has-text-color has-link-color wp-elements-92d29ad9832271c2f877b9b106aa71f8\" style=\"text-transform:uppercase\">TYPES DE TRAITEMENT<\/h5>\n\n\n\n<h2 class=\"wp-block-heading\">Des machines pour tous les types de traitement<\/h2>\n\n<\/div>\n    <\/div>\n\n\n    <div class=\"oi-block oi-block-layout-row row  justify-content-between row-vertical-gap-small\">\n        \n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-6 col-xl-6 col-xxl-5\" style=\"\" >\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"font-style:normal;font-weight:400\">MIA Food Tech fabrique des machines destin\u00e9es \u00e0 l'industrie alimentaire avec une attention particuli\u00e8re pour des produits tels que les compl\u00e9ments alimentaires, le chocolat, les pralines, les drag\u00e9es, le nougat, la nougatine, les confitures, les en-cas \u00e0 base de c\u00e9r\u00e9ales, de muesli et de fruits secs.<\/h4>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-secondary-color has-text-color has-link-color wp-elements-966dedff666c8ff5074d7b93464b978d\">\u2014 Traitement des mati\u00e8res premi\u00e8res<\/h4>\n\n\n\n<h4 class=\"wp-block-heading has-secondary-color has-text-color has-link-color wp-elements-f3a983cbfc69c3f45d7fa78f1be3e7e7\">\u2014 Pr\u00e9paration des sucreries<\/h4>\n\n\n\n<h4 class=\"wp-block-heading has-secondary-color has-text-color has-link-color wp-elements-b19ecb64bcf613bb9be2675968b66fbe\">\u2014 Traitement du produit fini<\/h4>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:1px; --oi-block-space-xl:1px; --oi-block-space-xxl:1px\"><\/div>\n\n<\/div>\n\n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-5 col-xl-5 col-xxl-5\" style=\"\" >\n<div class=\"oi-block oi-block-layout-menu\" ><div class=\"menu-menu-prodotti-per-lavorazione-fr-container\"><ul id=\"menu-menu-prodotti-per-lavorazione-fr\" class=\"oi-menu theme-with-arrows\"><li id=\"menu-item-10464\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10464\"><a href=\"https:\/\/miaft.com\/fr\/processing\/torrefaction-et-pelage\/\">Torr\u00e9faction et pelage<\/a><\/li>\n<li id=\"menu-item-10465\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10465\"><a href=\"https:\/\/miaft.com\/fr\/processing\/tri\/\">Tri<\/a><\/li>\n<li id=\"menu-item-10451\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10451\"><a href=\"https:\/\/miaft.com\/fr\/processing\/broyage\/\">Broyage<\/a><\/li>\n<li id=\"menu-item-10459\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10459\"><a href=\"https:\/\/miaft.com\/fr\/processing\/pre-raffinage\/\">Pr\u00e9-raffinage<\/a><\/li>\n<li id=\"menu-item-10462\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10462\"><a href=\"https:\/\/miaft.com\/fr\/processing\/raffinage\/\">Raffinage<\/a><\/li>\n<li id=\"menu-item-10463\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10463\"><a href=\"https:\/\/miaft.com\/fr\/processing\/stockage\/\">Stockage<\/a><\/li>\n<li id=\"menu-item-10454\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10454\"><a href=\"https:\/\/miaft.com\/fr\/processing\/doseurs\/\">Doseurs<\/a><\/li>\n<li id=\"menu-item-10457\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10457\"><a href=\"https:\/\/miaft.com\/fr\/processing\/extrusion-fr\/\">Extrusion<\/a><\/li>\n<li id=\"menu-item-10460\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10460\"><a href=\"https:\/\/miaft.com\/fr\/processing\/presses-fr\/\">Presses<\/a><\/li>\n<li id=\"menu-item-10456\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10456\"><a href=\"https:\/\/miaft.com\/fr\/processing\/pralinage\/\">Pralinage<\/a><\/li>\n<li id=\"menu-item-10455\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10455\"><a href=\"https:\/\/miaft.com\/fr\/processing\/drageification\/\">Drag\u00e9ification<\/a><\/li>\n<li id=\"menu-item-10453\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10453\"><a href=\"https:\/\/miaft.com\/fr\/processing\/cuisson\/\">Cuisson<\/a><\/li>\n<li id=\"menu-item-10458\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10458\"><a href=\"https:\/\/miaft.com\/fr\/processing\/laminage-et-coupe\/\">Laminage et coupe<\/a><\/li>\n<li id=\"menu-item-10450\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10450\"><a href=\"https:\/\/miaft.com\/fr\/processing\/battage\/\">Battage<\/a><\/li>\n<li id=\"menu-item-10452\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10452\"><a href=\"https:\/\/miaft.com\/fr\/processing\/criblage\/\">Criblage<\/a><\/li>\n<li id=\"menu-item-10466\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-10466\"><a href=\"https:\/\/miaft.com\/fr\/processing\/temperage\/\">Temp\u00e9rage<\/a><\/li>\n<li id=\"menu-item-13165\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-13165\"><a href=\"https:\/\/miaft.com\/fr\/processing\/enrobage\/\">Enrobage<\/a><\/li>\n<li id=\"menu-item-30896\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-30896\"><a href=\"https:\/\/miaft.com\/fr\/processing\/conchage\/\">Conchage<\/a><\/li>\n<li id=\"menu-item-35417\" class=\"menu-item menu-item-type-taxonomy menu-item-object-processing menu-item-35417\"><a href=\"https:\/\/miaft.com\/fr\/processing\/refroidissement\/\">Refroidissement<\/a><\/li>\n<\/ul><\/div><\/div>\n<\/div>\n    <\/div>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:60px; --oi-block-space-sm:75px; --oi-block-space-md:90px; --oi-block-space-lg:200px; --oi-block-space-xl:200px; --oi-block-space-xxl:200px\"><\/div>\n\n<\/div><\/div>\n\n\n<div class=\"oi-block oi-block-layout-container container\" style=\"\"  >\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:60px; --oi-block-space-sm:75px; --oi-block-space-md:90px; --oi-block-space-lg:150px; --oi-block-space-xl:149px; --oi-block-space-xxl:150px\"><\/div>\n\n\n<div class=\"oi-block oi-block-products-carousel\" ><div class=\"products-carousel-wrapper theme-light\">\n<div class=\"row mb-4 mb-sm-5\">\n    <div class=\"col-12 col-lg-6 col-xl-7 mb-4 mb-lg-0\">\n                    <h5 class=\"color-primary text-uppercase mb-2\">\n                PRODUITS\u00a0            <\/h5>\n                            <h2 class=\"mb-0\">\n                Machines et installations            <\/h2>\n                            <p class=\"mt-3\">La large gamme de machines propos\u00e9es par MIA Food Tech offre \u00e0 ses clients la possibilit\u00e9 de choisir celles qui conviennent le mieux \u00e0 leurs besoins. Nous pouvons concevoir des \u00e9quipements pour la production de nougat, de nougatine, de pralin\u00e9, de drag\u00e9es, de chocolat, de barres \u00e9nerg\u00e9tiques, de c\u00e9r\u00e9ales et de fruits secs.<\/p>\n            <\/div>\n    <div class=\"d-flex align-items-end justify-content-lg-end col-12 col-lg-6 col-xl-5\">\n        <div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/tutti-i-prodotti\/\" title=\"Voir tous\" class=\"btn btn-light-fill btn-type-default \" >\n    Voir tous    <\/a><\/div>        <div class=\"carousel-nav\">\n            <div class=\"nav-prev\">\n                <svg aria-label=\"nav-prev\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9.86\" height=\"16.892\" viewBox=\"0 0 9.86 16.892\">\n                    <path d=\"M1487.417,1272.4l7.739-7.739,7.739,7.739\" transform=\"translate(-1263.243 1503.602) rotate(-90)\" fill=\"none\" stroke=\"#000\" stroke-width=\"2\" \/>\n                <\/svg>\n            <\/div>\n            <div class=\"nav-next\">\n                <svg aria-label=\"nav-next\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9.86\" height=\"16.892\" viewBox=\"0 0 9.86 16.892\">\n                    <path d=\"M1487.417,1272.4l7.739-7.739,7.739,7.739\" transform=\"translate(-1263.243 1503.602) rotate(-90)\" fill=\"none\" stroke=\"#000\" stroke-width=\"2\" \/>\n                <\/svg>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    <div class=\"splide products-carousel\">\n        <div class=\"splide__track\">\n            <ul class=\"splide__list\">\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-product-miniature \">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/linea-professional-creme-spalmabili\/\">\n            <img decoding=\"async\" width=\"767\" height=\"518\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/linee-professional-creme-spalmabili-completa-767x518.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/linee-professional-creme-spalmabili-completa-767x518.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/linee-professional-creme-spalmabili-completa-150x101.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/linee-professional-creme-spalmabili-completa-575x388.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/linee-professional-creme-spalmabili-completa-991x669.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/linee-professional-creme-spalmabili-completa-1199x810.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/linee-professional-creme-spalmabili-completa.jpg 1500w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\" style=\"border: 2px solid #dc6529;\">P\u00e2tes et cr\u00e8mes \u00e0 tartiner<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n            <\/div>\n    <div class=\"post-main\">\n                    <h6 class=\"font-weight-bold text-uppercase color-primary\">Roaster-100E + PM120 + PRE-500 + MILL100 + ML500<\/h6>\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/linea-professional-creme-spalmabili\/\" title=\"Ligne professionnelle de cr\u00e9meures \u00e0 tartiner\">\n            <h4 class=\"mb-0 post-title\">Ligne professionnelle de cr\u00e9meures \u00e0 tartiner<\/h4>\n        <\/a>\n\n                    <h6 class=\"font-weight-regular mb-0 mt-2\">syst\u00e8me cl\u00e9 en main pour la production de cr\u00e8mes \u00e0 tartiner jusqu'\u00e0 800 kg\/jour<\/h6>\n            <\/div>\n    <\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-product-miniature \">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/premacinatore-pm120\/\">\n            <img decoding=\"async\" width=\"767\" height=\"926\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-767x926.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-767x926.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-1273x1536.jpg 1273w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-150x181.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-575x694.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-991x1196.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-1199x1447.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60.jpg 1386w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\" style=\"border: 2px solid #dc6529;\">P\u00e2tes et cr\u00e8mes \u00e0 tartiner<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n            <\/div>\n    <div class=\"post-main\">\n                    <h6 class=\"font-weight-bold text-uppercase color-primary\">PM120<\/h6>\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/premacinatore-pm120\/\" title=\"Pr\u00e9broyeur\">\n            <h4 class=\"mb-0 post-title\">Pr\u00e9broyeur<\/h4>\n        <\/a>\n\n                    <h6 class=\"font-weight-regular mb-0 mt-2\">solution pour le pr\u00e9broyage des noix et des f\u00e8ves de cacao<\/h6>\n            <\/div>\n    <\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-product-miniature \">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/scioglitore-industriale-per-cioccolato-paste-e-creme-ml500\/\">\n            <img decoding=\"async\" width=\"767\" height=\"767\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-scioglitore-tank-ml500-767x767.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-scioglitore-tank-ml500-767x767.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-scioglitore-tank-ml500-150x150.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-scioglitore-tank-ml500-575x575.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-scioglitore-tank-ml500-991x991.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-scioglitore-tank-ml500-1199x1199.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-scioglitore-tank-ml500.jpg 1501w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\" style=\"border: 2px solid #b2a0cd;\">Chocolat<\/h6>\n                        <\/div>\n                                            <div>\n                            <h6 class=\"post-term\" style=\"border: 2px solid #dc6529;\">P\u00e2tes et cr\u00e8mes \u00e0 tartiner<\/h6>\n                        <\/div>\n                                            <div>\n                            <h6 class=\"post-term\" style=\"border: 2px solid #fdc41f;\">Pralin\u00e9s et drag\u00e9es<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n            <\/div>\n    <div class=\"post-main\">\n                    <h6 class=\"font-weight-bold text-uppercase color-primary\">ML500<\/h6>\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/scioglitore-industriale-per-cioccolato-paste-e-creme-ml500\/\" title=\"Fondreur industrielle pour chocolat, p\u00e2tes et cr\u00e8mes\u00a0\">\n            <h4 class=\"mb-0 post-title\">Fondreur industrielle pour chocolat, p\u00e2tes et cr\u00e8mes\u00a0<\/h4>\n        <\/a>\n\n                    <h6 class=\"font-weight-regular mb-0 mt-2\">stockage et fusion \u00e0 temp\u00e9rature contr\u00f4l\u00e9e pour chocolat et cr\u00e8mes<\/h6>\n            <\/div>\n    <\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-product-miniature \">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/pre-miscelatore-pre-500\/\">\n            <img decoding=\"async\" width=\"767\" height=\"767\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-pre-mixer-pre-500-767x767.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-pre-mixer-pre-500-767x767.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-pre-mixer-pre-500-150x150.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-pre-mixer-pre-500-575x575.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-pre-mixer-pre-500-991x991.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-pre-mixer-pre-500-1199x1199.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2026\/04\/mia-pre-mixer-pre-500.jpg 1500w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\" style=\"border: 2px solid #dc6529;\">Frutta secca<\/h6>\n                        <\/div>\n                                            <div>\n                            <h6 class=\"post-term\" style=\"border: 2px solid #dc6529;\">P\u00e2tes et cr\u00e8mes \u00e0 tartiner<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n            <\/div>\n    <div class=\"post-main\">\n                    <h6 class=\"font-weight-bold text-uppercase color-primary\">PRE-500<\/h6>\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/pre-miscelatore-pre-500\/\" title=\"Pr\u00e9m\u00e9langeur\">\n            <h4 class=\"mb-0 post-title\">Pr\u00e9m\u00e9langeur<\/h4>\n        <\/a>\n\n                    <h6 class=\"font-weight-regular mb-0 mt-2\">homog\u00e9n\u00e9isation et maintien de la temp\u00e9rature des p\u00e2tes et tartinades<\/h6>\n            <\/div>\n    <\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-product-miniature \">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/conca-150-2\/\">\n            <img decoding=\"async\" width=\"767\" height=\"767\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-conca-150-1-767x767.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-conca-150-1-767x767.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-conca-150-1-150x150.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-conca-150-1-575x575.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-conca-150-1-991x991.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-conca-150-1-1199x1199.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-conca-150-1.jpg 1500w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\" style=\"border: 2px solid #b2a0cd;\">Chocolat<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n            <\/div>\n    <div class=\"post-main\">\n                    <h6 class=\"font-weight-bold text-uppercase color-primary\">CH 150 \/ CH 250<\/h6>\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/conca-150-2\/\" title=\"Conch\">\n            <h4 class=\"mb-0 post-title\">Conch<\/h4>\n        <\/a>\n\n                    <h6 class=\"font-weight-regular mb-0 mt-2\">Fondoir et m\u00e9langeur de chocolat professionnel pour conchage<\/h6>\n            <\/div>\n    <\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-product-miniature \">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/tostino-15kg-roaster-15-eco-roaster-15-pro\/\">\n            <img decoding=\"async\" width=\"767\" height=\"767\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-roaster-15-pro-767x767.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-roaster-15-pro-767x767.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-roaster-15-pro-150x150.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-roaster-15-pro-575x575.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-roaster-15-pro-991x991.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-roaster-15-pro-1199x1199.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-roaster-15-pro.jpg 1500w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\" style=\"border: 2px solid #dc6529;\">Fruits secs<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n            <\/div>\n    <div class=\"post-main\">\n                    <h6 class=\"font-weight-bold text-uppercase color-primary\">ROASTER-15 ECO, ROASTER-15 PRO<\/h6>\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/tostino-15kg-roaster-15-eco-roaster-15-pro\/\" title=\"Torr\u00e9facteur 15 kg\u00a0\">\n            <h4 class=\"mb-0 post-title\">Torr\u00e9facteur 15 kg\u00a0<\/h4>\n        <\/a>\n\n                    <h6 class=\"font-weight-regular mb-0 mt-2\">torr\u00e9faction des fruits secs et des graines ol\u00e9agineuses <\/h6>\n            <\/div>\n    <\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-product-miniature \">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/premacinatore-pm60\/\">\n            <img decoding=\"async\" width=\"767\" height=\"926\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-767x926.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-767x926.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-1273x1536.jpg 1273w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-150x181.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-575x694.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-991x1196.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60-1199x1447.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-premacinatore-pm60.jpg 1386w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\" style=\"border: 2px solid #dc6529;\">P\u00e2tes et cr\u00e8mes \u00e0 tartiner<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n            <\/div>\n    <div class=\"post-main\">\n                    <h6 class=\"font-weight-bold text-uppercase color-primary\">PM60<\/h6>\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/premacinatore-pm60\/\" title=\"Pr\u00e9-broyeur\u00a0\">\n            <h4 class=\"mb-0 post-title\">Pr\u00e9-broyeur\u00a0<\/h4>\n        <\/a>\n\n                    <h6 class=\"font-weight-regular mb-0 mt-2\">pour le pr\u00e9-broyage des fruits secs et des f\u00e8ves de cacao <\/h6>\n            <\/div>\n    <\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-product-miniature \">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/granellatrice-automatica-crick-crock-100-2t-100-3t-100-4t\/\">\n            <img decoding=\"async\" width=\"767\" height=\"978\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-granellatrice-automatica-crick-crock-100-2t-100-4t-100-6t-767x978.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-granellatrice-automatica-crick-crock-100-2t-100-4t-100-6t-767x978.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-granellatrice-automatica-crick-crock-100-2t-100-4t-100-6t-1204x1536.jpg 1204w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-granellatrice-automatica-crick-crock-100-2t-100-4t-100-6t-150x191.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-granellatrice-automatica-crick-crock-100-2t-100-4t-100-6t-575x733.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-granellatrice-automatica-crick-crock-100-2t-100-4t-100-6t-991x1264.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-granellatrice-automatica-crick-crock-100-2t-100-4t-100-6t-1199x1529.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/09\/mia-granellatrice-automatica-crick-crock-100-2t-100-4t-100-6t.jpg 1314w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\" style=\"border: 2px solid #dc6529;\">Fruits secs<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n            <\/div>\n    <div class=\"post-main\">\n                    <h6 class=\"font-weight-bold text-uppercase color-primary\">CRICK-CROCK 100-2T - 100-3T - 100-4T<\/h6>\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/product\/granellatrice-automatica-crick-crock-100-2t-100-3t-100-4t\/\" title=\"Broyeur automatique\u00a0\">\n            <h4 class=\"mb-0 post-title\">Broyeur automatique\u00a0<\/h4>\n        <\/a>\n\n                    <h6 class=\"font-weight-regular mb-0 mt-2\">pour fruits secs, noisettes, nougat, nougatine, biscuits et sucreries <\/h6>\n            <\/div>\n    <\/div>                    <\/li>\n                                            <\/ul>\n        <\/div>\n        <div class=\"carousel-progress mt-5\">\n            <div class=\"carousel-progress-bar\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n<\/div>\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:60px; --oi-block-space-sm:60px; --oi-block-space-md:75px; --oi-block-space-lg:90px; --oi-block-space-xl:120px; --oi-block-space-xxl:150px\"><\/div>\n\n<\/div>\n\n\n<div class=\"wp-block-group has-light-background-color has-background is-layout-flow wp-block-group-is-layout-flow\"><div class=\"oi-block oi-block-layout-container container\" style=\"\"  >\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:60px; --oi-block-space-sm:60px; --oi-block-space-md:75px; --oi-block-space-lg:90px; --oi-block-space-xl:120px; --oi-block-space-xxl:150px\"><\/div>\n\n\n    <div class=\"oi-block oi-block-layout-row row  \">\n        \n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-10 col-xl-10 col-xxl-9\" style=\"\" >\n\n<h5 class=\"wp-block-heading has-primary-color has-text-color has-link-color wp-elements-aedccd6a2a1b49c3b86f9d3d24960987\" style=\"text-transform:uppercase\">L\u2019ENTREPRISE<\/h5>\n\n\n\n<h2 class=\"wp-block-heading\">Machines pour le traitement des fruits secs et des sucreries<\/h2>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n<\/div>\n    <\/div>\n\n\n    <div class=\"oi-block oi-block-layout-row row  justify-content-between row-vertical-gap-small\">\n        \n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-6 col-xl-6 col-xxl-5\" style=\"\" >\n\n<h4 class=\"wp-block-heading\" style=\"font-style:normal;font-weight:400\">L'exp\u00e9rience et les connaissances techniques ont conduit MIA \u00e0 r\u00e9aliser un vaste catalogue de production allant des machines individuelles (autonomes) aux lignes enti\u00e8rement automatiques en passant par les installations cl\u00e9s en main.<\/h4>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/09\/servizio-assistenza.svg\" alt=\"\" class=\"wp-image-28624\"\/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\" style=\"text-transform:uppercase\">SERVICE D'ASSISTANCE<br>TECHNIQUE EN ITALIE ET \u00c0 L'\u00c9TRANGER<\/h5>\n<\/div>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-7 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/09\/robusti.svg\" alt=\"\" class=\"wp-image-28619\"\/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\" style=\"text-transform:uppercase\">DES MACHINES SIMPLES ET ROBUSTES<\/h5>\n<\/div>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-8 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/09\/formazione.svg\" alt=\"\" class=\"wp-image-28614\"\/><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\" style=\"text-transform:uppercase\">UN CATALOGUE RICHE ET VARI\u00c9<\/h5>\n<\/div>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n<div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/azienda\/\" title=\"\" class=\"btn btn-white-fill btn-type-shadow \" >\n    D\u00e9couvrez l'entreprise    <\/a><\/div>\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:60px; --oi-block-space-sm:30px; --oi-block-space-md:50px; --oi-block-space-lg:1px; --oi-block-space-xl:1px; --oi-block-space-xxl:1px\"><\/div>\n\n<\/div>\n\n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-6 col-xl-6 col-xxl-6\" style=\"\" >\n<div class=\"oi-block oi-block-link-group\" ><a class=\"\" href=\"https:\/\/miaft.com\/fr\/machine\/stand-alone\/\">\n    \n\n<div class=\"wp-block-group btn-type-shadow has-white-background-color has-background oi-anim is-layout-flow wp-block-group-is-layout-flow\" style=\"border-radius:10px;padding:30px 30px 30px 30px\" data-oi-anim=\"fade-up\" data-oi-anim-delay=\"0.1\">    <div class=\"oi-block oi-block-layout-row row  align-items-center\">\n        \n<div class=\"oi-block oi-block-layout-row-column text-center col-12 col-sm-12 col-md-12 col-lg-5 col-xl-6 col-xxl-6\" style=\"\" >\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1421\" height=\"1500\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-temperatrice-cioccolato-120kg-max-tm120-max-1.jpg\" alt=\"temperatrice cioccolato 120 kg max\" class=\"wp-image-29489\" style=\"width:auto;height:250px\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-temperatrice-cioccolato-120kg-max-tm120-max-1.jpg 1421w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-temperatrice-cioccolato-120kg-max-tm120-max-1-150x158.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-temperatrice-cioccolato-120kg-max-tm120-max-1-575x607.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-temperatrice-cioccolato-120kg-max-tm120-max-1-767x810.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-temperatrice-cioccolato-120kg-max-tm120-max-1-991x1046.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-temperatrice-cioccolato-120kg-max-tm120-max-1-1199x1266.jpg 1199w\" sizes=\"auto, (max-width: 1421px) 100vw, 1421px\" \/><\/figure>\n\n<\/div>\n\n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-7 col-xl-6 col-xxl-6\" style=\"\" >\n\n<h4 class=\"wp-block-heading text-center text-lg-start\">Machines autonomes<\/h4>\n\n<\/div>\n    <\/div>\n<\/div>\n\n<\/a><\/div>\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n<div class=\"oi-block oi-block-link-group\" ><a class=\"\" href=\"https:\/\/miaft.com\/fr\/machine\/linee-automatiche\/\">\n    \n\n<div class=\"wp-block-group btn-type-shadow has-white-background-color has-background oi-anim is-layout-flow wp-block-group-is-layout-flow\" style=\"border-radius:10px;padding:30px 30px 30px 30px\" data-oi-anim=\"fade-up\" data-oi-anim-delay=\"0.1\">    <div class=\"oi-block oi-block-layout-row row  align-items-center\">\n        \n<div class=\"oi-block oi-block-layout-row-column text-center col-12 col-sm-12 col-md-12 col-lg-5 col-xl-6 col-xxl-6\" style=\"\" >\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"312\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/mia_catalogo-linee-automatiche.png\" alt=\"mia catalogo linee automatiche\" class=\"wp-image-2580\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/mia_catalogo-linee-automatiche.png 400w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/mia_catalogo-linee-automatiche-150x117.png 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n<\/div>\n\n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-7 col-xl-6 col-xxl-6\" style=\"\" >\n\n<h4 class=\"wp-block-heading text-center text-lg-start\">Lignes automatiques<\/h4>\n\n<\/div>\n    <\/div>\n<\/div>\n\n<\/a><\/div>\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n<div class=\"oi-block oi-block-link-group\" ><a class=\"\" href=\"https:\/\/miaft.com\/fr\/machine\/impianti-chiavi-in-mano\/\">\n    \n\n<div class=\"wp-block-group btn-type-shadow has-white-background-color has-background oi-anim is-layout-flow wp-block-group-is-layout-flow\" style=\"border-radius:10px;padding:30px 30px 30px 30px\" data-oi-anim=\"fade-up\" data-oi-anim-delay=\"0.1\">    <div class=\"oi-block oi-block-layout-row row  align-items-center\">\n        \n<div class=\"oi-block oi-block-layout-row-column text-center col-12 col-sm-12 col-md-12 col-lg-5 col-xl-6 col-xxl-6\" style=\"\" >\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"312\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/mia_catalogo-impianti-chiavi-in-mano.png\" alt=\"mia catalogo impianti chiavi in mano\" class=\"wp-image-2586\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/mia_catalogo-impianti-chiavi-in-mano.png 400w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/mia_catalogo-impianti-chiavi-in-mano-150x117.png 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n<\/div>\n\n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-7 col-xl-6 col-xxl-6\" style=\"\" >\n\n<h4 class=\"wp-block-heading text-center text-lg-start\">Installations cl\u00e9 en main<\/h4>\n\n<\/div>\n    <\/div>\n<\/div>\n\n<\/a><\/div>\n<\/div>\n    <\/div>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:60px; --oi-block-space-sm:60px; --oi-block-space-md:75px; --oi-block-space-lg:90px; --oi-block-space-xl:120px; --oi-block-space-xxl:150px\"><\/div>\n\n\n\n<div class=\"wp-block-group d-none has-white-color has-dark-background-color has-text-color has-background oi-anim has-custom-sizing is-layout-flow wp-block-group-is-layout-flow\" style=\"border-radius:10px;--oi-style-padding-xs:0px 30px 0px 30px;--oi-style-padding-sm:0px 30px 0px 30px;--oi-style-padding-md:0px 30px 0px 30px;background-image:url(&#039;https:\/\/miaft.com\/wp-content\/uploads\/2023\/12\/home-bg-torrone-min.jpg&#039;);background-size:cover;\" data-oi-anim=\"fade-up\" data-oi-anim-delay=\"0.1\">    <div class=\"oi-block oi-block-layout-row row  justify-content-center\">\n        \n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-10 col-xl-9 col-xxl-9\" style=\"\" >\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:45px; --oi-block-space-md:75px; --oi-block-space-lg:90px; --oi-block-space-xl:150px; --oi-block-space-xxl:150px\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading has-white-color has-text-color has-link-color wp-elements-3401bbbef6061bcbebcb0b8b970c1481\" style=\"text-transform:uppercase\">Acad\u00e9mie Mia<\/h5>\n\n\n\n<h3 class=\"wp-block-heading\">Cours de formation professionnelle<\/h3>\n\n\n    <div class=\"oi-block oi-block-layout-row row  \">\n        \n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-10 col-xl-8 col-xxl-8\" style=\"\" >\n\n<p>Cours en groupe ou sur mesure pour la production de produits de confiserie avec des recettes standard ou sp\u00e9cifiques au client dans le laboratoire de MIA FOOD TECH.<\/p>\n\n<\/div>\n    <\/div>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n<div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/corsi-di-formazione\/\" title=\"\" class=\"btn-white btn-type-arrow \" >\n    D\u00e9couvrez            <span class=\"icon-arrow\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\">\n                <path d=\"M8,0,6.545,1.455l5.506,5.506H0V9.039H12.052L6.545,14.545,8,16l8-8Z\" fill=\"currentColor\" \/>\n            <\/svg>\n        <\/span>\n    <\/a><\/div>\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:45px; --oi-block-space-md:75px; --oi-block-space-lg:90px; --oi-block-space-xl:150px; --oi-block-space-xxl:150px\"><\/div>\n\n<\/div>\n    <\/div>\n<\/div>\n\n<\/div><\/div>\n\n\n\n<div style=\"background-image:url(&#039;https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/sfondo-mia-lab.jpg&#039;);background-position:50% 50%;background-size:cover;\" class=\"wp-block-group has-secondary-color has-text-color has-link-color wp-elements-ca7ef28f23ab7c9ca0027743eae557f7 is-layout-flow wp-block-group-is-layout-flow has-background\"><div class=\"oi-block oi-block-layout-container container\" style=\"\"  >\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:75px; --oi-block-space-sm:90px; --oi-block-space-md:90px; --oi-block-space-lg:120px; --oi-block-space-xl:120px; --oi-block-space-xxl:120px\"><\/div>\n\n\n<div class=\"oi-block oi-block-background-block\" ><div class=\"background-block \">\n    <img decoding=\"async\" width=\"1500\" height=\"681\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab.jpg\" class=\"featured-image d-none d-lg-block\" alt=\"mia-lab.jpg\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab.jpg 1500w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab-150x68.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab-575x261.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab-767x348.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab-991x450.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab-1199x544.jpg 1199w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/>    <img decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab-termometro-formazione-mobile.jpg\" class=\"featured-image d-lg-none\" alt=\"mia-lab-termometro-formazione-mobile.jpg\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab-termometro-formazione-mobile.jpg 1080w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab-termometro-formazione-mobile-864x1536.jpg 864w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab-termometro-formazione-mobile-150x267.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab-termometro-formazione-mobile-575x1022.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab-termometro-formazione-mobile-767x1364.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-lab-termometro-formazione-mobile-991x1762.jpg 991w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>    \n    <div class=\"oi-block oi-block-layout-row row  \">\n        \n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-8 col-xl-8 col-xxl-7\" style=\"\" >\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mialab-logo-white.svg\" alt=\"mialab logo white\" class=\"wp-image-33641\" style=\"width:450px\"\/><\/figure>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-headingSize-h3-60 h3-60\">Cours de formation professionnelle<\/h3>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n\n<p>Cours en groupe ou sur mesure pour la production de produits de confiserie avec des recettes standard ou sp\u00e9cifiques au client dans le laboratoire de MIA FOOD TECH.<\/p>\n\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:30px; --oi-block-space-sm:30px; --oi-block-space-md:30px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n\n<div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/corsi-di-formazione\/\" title=\"\" class=\"btn-white btn-type-arrow \" >\n    D\u00e9couvrez            <span class=\"icon-arrow\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\">\n                <path d=\"M8,0,6.545,1.455l5.506,5.506H0V9.039H12.052L6.545,14.545,8,16l8-8Z\" fill=\"currentColor\" \/>\n            <\/svg>\n        <\/span>\n    <\/a><\/div>\n<\/div>\n    <\/div>\n\n<\/div><\/div>\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:75px; --oi-block-space-sm:90px; --oi-block-space-md:90px; --oi-block-space-lg:120px; --oi-block-space-xl:120px; --oi-block-space-xxl:120px\"><\/div>\n\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group has-light-background-color has-background is-layout-flow wp-block-group-is-layout-flow\"><div class=\"oi-block oi-block-layout-container container\" style=\"\"  >\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:60px; --oi-block-space-sm:60px; --oi-block-space-md:75px; --oi-block-space-lg:90px; --oi-block-space-xl:120px; --oi-block-space-xxl:150px\"><\/div>\n\n\n<div class=\"oi-block oi-block-blog-post-carousel\" ><div class=\"row mb-4 mb-sm-5\">\n    <div class=\"col-12 col-lg-6 col-xl-8 mb-4 mb-lg-0\">\n                    <h5 class=\"color-primary text-uppercase mb-2\">\n                NOUVEAUT\u00c9S\u00a0            <\/h5>\n                            <h2 class=\"mb-0\">\n                D\u00e9couvrez les derni\u00e8res nouveaut\u00e9s            <\/h2>\n                    <\/div>\n    <div class=\"d-flex align-items-end justify-content-lg-end col-12 col-lg-6 col-xl-4\">\n        <div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/novita-eventi-e-formazione\/\" title=\"Voir tous\" class=\"btn btn-white-fill btn-type-shadow \" >\n    Voir tous    <\/a><\/div>                    <div class=\"carousel-nav\">\n                <div class=\"nav-prev\">\n                    <svg aria-label=\"nav-prev\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9.86\" height=\"16.892\" viewBox=\"0 0 9.86 16.892\">\n                        <path d=\"M1487.417,1272.4l7.739-7.739,7.739,7.739\" transform=\"translate(-1263.243 1503.602) rotate(-90)\" fill=\"none\" stroke=\"#000\" stroke-width=\"2\" \/>\n                    <\/svg>\n                <\/div>\n                <div class=\"nav-next\">\n                    <svg aria-label=\"nav-next\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"9.86\" height=\"16.892\" viewBox=\"0 0 9.86 16.892\">\n                        <path d=\"M1487.417,1272.4l7.739-7.739,7.739,7.739\" transform=\"translate(-1263.243 1503.602) rotate(-90)\" fill=\"none\" stroke=\"#000\" stroke-width=\"2\" \/>\n                    <\/svg>\n                <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n    <div class=\"splide blog-post-carousel\">\n        <div class=\"splide__track\">\n            <ul class=\"splide__list\">\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-blog-post-miniature post-type-news\">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/mia-al-sigep-2026-innovazione-al-servizio-dellindustria-dolciaria\/\">\n            <img decoding=\"async\" width=\"767\" height=\"431\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en-767x431.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en-1199x674.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en.jpg 1920w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\">Ev\u00e9nements<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"post-main\">\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/mia-al-sigep-2026-innovazione-al-servizio-dellindustria-dolciaria\/\" title=\"MIA au SIGEP 2026\u00a0: L\u2019innovation au service de l\u2019industrie de la confiserie\">\n            <h4 class=\"mb-0 post-title\">MIA au SIGEP 2026\u00a0: L\u2019innovation au service de l\u2019industrie de la confiserie<\/h4>\n        <\/a>\n\n        \n                    <p class=\"h6 font-weight-regular mt-3\">Du 16 au 20 janvier 2026, MIA participera au SIGEP, le salon international de r\u00e9f\u00e9rence pour les technologies et les tendances de l\u2019industrie de la confiserie. C\u2019est une occasion strat\u00e9gique de pr\u00e9senter nos solutions pour la production de confiseries.<\/p>\n            <\/div>\n<\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-blog-post-miniature post-type-news\">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/venez-nous-rendre-visite-a-gulfood-manufacturing-2025\/\">\n            <img decoding=\"async\" width=\"767\" height=\"431\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-news-gulfood-2025-767x431.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-news-gulfood-2025-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-news-gulfood-2025-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-news-gulfood-2025-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-news-gulfood-2025-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-news-gulfood-2025-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-news-gulfood-2025-1199x674.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-news-gulfood-2025.jpg 1920w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\">Ev\u00e9nements<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"post-main\">\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/venez-nous-rendre-visite-a-gulfood-manufacturing-2025\/\" title=\"Venez nous rendre visite \u00e0 GULFOOD MANUFACTURING 2025\">\n            <h4 class=\"mb-0 post-title\">Venez nous rendre visite \u00e0 GULFOOD MANUFACTURING 2025<\/h4>\n        <\/a>\n\n        \n                    <p class=\"h6 font-weight-regular mt-3\">Du 4 au 6 novembre, nous serons pr\u00e9sents au salon Gulfood Manufacturing 2025, l'un des plus importants \u00e9v\u00e9nements internationaux d\u00e9di\u00e9s \u00e0 l'innovation et aux technologies pour l'industrie agroalimentaire.\n\nSTAND S2-D4 SHK SAEED HALL 2<\/p>\n            <\/div>\n<\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-blog-post-miniature post-type-news\">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/mia-food-tech-si-rinnova\/\">\n            <img decoding=\"async\" width=\"767\" height=\"431\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-nuovo-logo-news-767x431.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-nuovo-logo-news-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-nuovo-logo-news-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-nuovo-logo-news-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-nuovo-logo-news-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-nuovo-logo-news-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-nuovo-logo-news-1199x674.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/10\/mia-food-tech-nuovo-logo-news.jpg 1920w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\">Nouvelles<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"post-main\">\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/mia-food-tech-si-rinnova\/\" title=\"Mia Food Tech se renouvelle\">\n            <h4 class=\"mb-0 post-title\">Mia Food Tech se renouvelle<\/h4>\n        <\/a>\n\n        \n                    <p class=\"h6 font-weight-regular mt-3\">C'est avec une immense fiert\u00e9 et une passion immenses que nous vous pr\u00e9sentons notre image enti\u00e8rement repens\u00e9e\u00a0: une refonte qui va bien au-del\u00e0 d'un simple changement de logo<\/p>\n            <\/div>\n<\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-blog-post-miniature post-type-news\">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/mia-food-tech-debutta-a-ipack-ima-2025\/\">\n            <img decoding=\"async\" width=\"767\" height=\"431\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/04\/mia-ipac-ima-processing-packaging-2025-fr-767x431.jpg\" class=\"img-fluid\" alt=\"mia ipac ima processing packaging 2025 fr\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/04\/mia-ipac-ima-processing-packaging-2025-fr-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/04\/mia-ipac-ima-processing-packaging-2025-fr-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/04\/mia-ipac-ima-processing-packaging-2025-fr-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/04\/mia-ipac-ima-processing-packaging-2025-fr-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/04\/mia-ipac-ima-processing-packaging-2025-fr-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/04\/mia-ipac-ima-processing-packaging-2025-fr-1199x674.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/04\/mia-ipac-ima-processing-packaging-2025-fr.jpg 1920w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\">Ev\u00e9nements<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"post-main\">\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/mia-food-tech-debutta-a-ipack-ima-2025\/\" title=\"MIA Food Tech fait ses d\u00e9buts \u00e0 IPACK-IMA 2025\">\n            <h4 class=\"mb-0 post-title\">MIA Food Tech fait ses d\u00e9buts \u00e0 IPACK-IMA 2025<\/h4>\n        <\/a>\n\n        \n                    <p class=\"h6 font-weight-regular mt-3\">Nous avons le plaisir d\u2019annoncer la premi\u00e8re participation de MIA Food Tech au salon IPACK-IMA, qui se tiendra du 27 au 30 mai 2025 \u00e0 Fiera Milano.<\/p>\n            <\/div>\n<\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-blog-post-miniature post-type-news\">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/vi-aspettiamo-al-sigep-2025\/\">\n            <img decoding=\"async\" width=\"767\" height=\"431\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/01\/mia-food-tech-sigep-2025-en-767x431.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/01\/mia-food-tech-sigep-2025-en-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/01\/mia-food-tech-sigep-2025-en-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/01\/mia-food-tech-sigep-2025-en-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/01\/mia-food-tech-sigep-2025-en-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/01\/mia-food-tech-sigep-2025-en-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/01\/mia-food-tech-sigep-2025-en-1199x674.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/01\/mia-food-tech-sigep-2025-en.jpg 1920w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\">Ev\u00e9nements<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"post-main\">\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/vi-aspettiamo-al-sigep-2025\/\" title=\"Nous vous attendons au SIGEP 2025!\">\n            <h4 class=\"mb-0 post-title\">Nous vous attendons au SIGEP 2025!<\/h4>\n        <\/a>\n\n        \n                    <p class=\"h6 font-weight-regular mt-3\">Nous sommes ravis d'annoncer notre participation au SIGEP 2025, qui se tiendra du 18 au 22 janvier au Rimini Fiera. O\u00f9 nous trouver: Pavillon B3 - Stand 026!<\/p>\n            <\/div>\n<\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-blog-post-miniature post-type-news\">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/nuova-partnership-tra-mia-food-tech-e-chocolate-world\/\">\n            <img decoding=\"async\" width=\"767\" height=\"511\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-macchinari-cioccolato-chocolate-world_lavorazione-767x511.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-macchinari-cioccolato-chocolate-world_lavorazione-767x511.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-macchinari-cioccolato-chocolate-world_lavorazione-1536x1024.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-macchinari-cioccolato-chocolate-world_lavorazione-150x100.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-macchinari-cioccolato-chocolate-world_lavorazione-575x383.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-macchinari-cioccolato-chocolate-world_lavorazione-991x661.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-macchinari-cioccolato-chocolate-world_lavorazione-1199x799.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/05\/mia-macchinari-cioccolato-chocolate-world_lavorazione.jpg 1920w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\">Nouvelles<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"post-main\">\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/nuova-partnership-tra-mia-food-tech-e-chocolate-world\/\" title=\"Nouveau partenariat entre Mia Food Tech et Chocolate World\">\n            <h4 class=\"mb-0 post-title\">Nouveau partenariat entre Mia Food Tech et Chocolate World<\/h4>\n        <\/a>\n\n        \n                    <p class=\"h6 font-weight-regular mt-3\">Mia Food Tech et Chocolate World unissent leurs forces pour offrir \u00e0 leurs clients une gamme de machines toujours plus \u00e9tendue et performante, d\u00e9finissant ainsi un nouveau niveau d'exp\u00e9rience client et d'efficacit\u00e9 op\u00e9rationnelle.<\/p>\n            <\/div>\n<\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-blog-post-miniature post-type-news\">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/articolo-industrie-alimentari-marzo-2024\/\">\n            <img decoding=\"async\" width=\"767\" height=\"523\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/04\/articolo-1-767x523.png\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/04\/articolo-1-767x523.png 767w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/04\/articolo-1-150x102.png 150w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/04\/articolo-1-575x392.png 575w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/04\/articolo-1-991x675.png 991w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/04\/articolo-1-1199x817.png 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/04\/articolo-1.png 1344w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\">Nouvelles<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"post-main\">\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/articolo-industrie-alimentari-marzo-2024\/\" title=\"Article &quot;Industries alimentaires&quot; mars 2024\">\n            <h4 class=\"mb-0 post-title\">Article \"Industries alimentaires\" mars 2024<\/h4>\n        <\/a>\n\n        \n                    <p class=\"h6 font-weight-regular mt-3\">Ils \u00e9crivent \u00e0 notre sujet :\n\"MIA Food Tech fabrique des machines d\u00e9di\u00e9es au secteur alimentaire avec une attention particuli\u00e8re pour les produits tels que : compl\u00e9ments alimentaires, chocolat, pralines, drag\u00e9es, nougat, croustillants, confitures, snacks \u00e0 base de c\u00e9r\u00e9ales, muesli et fruits secs...\"<\/p>\n            <\/div>\n<\/div>                    <\/li>\n                                    <li class=\"splide__slide\">\n                        <div class=\"single-blog-post-miniature post-type-news\">\n    <div class=\"thumbnail-container\">\n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/vieni-a-trovarci-al-prosweets-2024\/\">\n            <img decoding=\"async\" width=\"767\" height=\"409\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/pro-sweets-cologne-2024-767x409.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/pro-sweets-cologne-2024-767x409.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/pro-sweets-cologne-2024-1536x819.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/pro-sweets-cologne-2024-150x80.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/pro-sweets-cologne-2024-575x307.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/pro-sweets-cologne-2024-991x529.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/pro-sweets-cologne-2024-1199x639.jpg 1199w, https:\/\/miaft.com\/wp-content\/uploads\/2024\/01\/pro-sweets-cologne-2024.jpg 1920w\" sizes=\"auto, (max-width: 767px) 100vw, 767px\" \/>        <\/a>\n        <div class=\"post-info\">\n                            <div class=\"post-terms\">\n                                            <div>\n                            <h6 class=\"post-term\">Ev\u00e9nements<\/h6>\n                        <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"post-main\">\n        \n        <a class=\"d-block\" href=\"https:\/\/miaft.com\/fr\/vieni-a-trovarci-al-prosweets-2024\/\" title=\"Visitez-nous \u00e0 PROSWEETS 2024\">\n            <h4 class=\"mb-0 post-title\">Visitez-nous \u00e0 PROSWEETS 2024<\/h4>\n        <\/a>\n\n        \n                    <p class=\"h6 font-weight-regular mt-3\">Mia Food Tech sera pr\u00e9sent au prochain salon PROSWEETS 2024 \u00e0 COLONIA (Allemagne). Venez nous rendre visite du 28 au 31 janvier 2024 ! HALL 10.1 - STAND D-068<\/p>\n            <\/div>\n<\/div>                    <\/li>\n                                            <\/ul>\n        <\/div>\n        <div class=\"carousel-progress mt-5\">\n            <div class=\"carousel-progress-bar\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:45px; --oi-block-space-sm:60px; --oi-block-space-md:75px; --oi-block-space-lg:90px; --oi-block-space-xl:120px; --oi-block-space-xxl:150px\"><\/div>\n\n<\/div><\/div>\n\n\n    <div id=\"#featured-post\" class=\"oi-block oi-block-popup modal fade theme-light space-no-padding open-onclick popup-size-large\" tabindex=\"-1\" aria-hidden=\"true\" data-reference=\"#featured-post\" data-opendelay=\"1.5\" data-remember-close-value=\"1\" data-remember-close-time=\"hours\">\n        <div class=\"modal-dialog modal-dialog-centered\">\n            <div class=\"modal-content\">\n                <div class=\"modal-body\">\n                    <button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><\/button>\n                    \n<div class=\"oi-block oi-block-featured-post\" >                    <div class=\"row\">\n            <div class=\"d-flex items-stretch col-12 col-lg-6\">\n                <div class=\"img-container\">\n                                            <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en.jpg\" class=\"img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en.jpg 1920w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en-1536x864.jpg 1536w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en-150x84.jpg 150w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en-575x323.jpg 575w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en-767x431.jpg 767w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en-991x557.jpg 991w, https:\/\/miaft.com\/wp-content\/uploads\/2025\/12\/mia-food-tech-news-sigep-2026-en-1199x674.jpg 1199w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>                                    <\/div>\n            <\/div>\n            <div class=\"d-flex offset-xl-1 col-12 col-lg-6 col-xl-4 ps-5 pe-5 ps-xl-0 pe-xl-0\">\n                <div class=\"my-auto py-4 py-sm-5\">\n                                            <h6 class=\"d-inline-block py-1 px-3 mb-3 font-weight-bold text-uppercase color-primary bg-light post-terms\">\n                            Ev\u00e9nements                        <\/h6>\n                    \n                    <a href=\"https:\/\/miaft.com\/fr\/mia-al-sigep-2026-innovazione-al-servizio-dellindustria-dolciaria\/\" title=\"En savoir plus - MIA au SIGEP 2026\u00a0: L\u2019innovation au service de l\u2019industrie de la confiserie\">\n                        <h3 class=\"post-title\">\n                            MIA au SIGEP 2026\u00a0: L\u2019innovation au service de l\u2019industrie de la confiserie                        <\/h3>\n                    <\/a>\n\n                    \n                    <div class=\"mt-3 post-excerpt\">\n                        Du 16 au 20 janvier 2026, MIA participera au SIGEP, le salon international de r\u00e9f\u00e9rence pour les technologies et les tendances de l\u2019industrie de la confiserie. C\u2019est une occasion strat\u00e9gique de pr\u00e9senter nos solutions pour la production de confiseries.                    <\/div>\n\n                    \n                    <div class=\"post-link mt-4\">\n                        <div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/mia-al-sigep-2026-innovazione-al-servizio-dellindustria-dolciaria\/\" title=\"\" class=\"btn btn-light-fill btn-type-shadow \" >\n    En savoir plus    <\/a><\/div>                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n        <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n\n    <div id=\"#featured-post\" class=\"oi-block oi-block-popup modal fade theme-light space-no-padding open-onclick popup-size-large\" tabindex=\"-1\" aria-hidden=\"true\" data-reference=\"#featured-post\" data-opendelay=\"1.5\" data-remember-close-value=\"4\" data-remember-close-time=\"hours\">\n        <div class=\"modal-dialog modal-dialog-centered\">\n            <div class=\"modal-content\">\n                <div class=\"modal-body\">\n                    <button type=\"button\" class=\"btn-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><\/button>\n                    \n\n<div class=\"wp-block-group has-white-background-color has-background is-layout-flow wp-block-group-is-layout-flow\">    <div class=\"oi-block oi-block-layout-row row  align-items-center\">\n        \n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-6 col-xl-6 col-xxl-6\" style=\"\" >\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\" style=\"background-image:url(&quot;https:\/\/miaft.com\/wp-content\/uploads\/2024\/06\/tm120-max-anteprima.gif&quot;);background-position:center;background-size:cover;background-repeat:no-repeat\">    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:300px; --oi-block-space-sm:300px; --oi-block-space-md:300px; --oi-block-space-lg:600px; --oi-block-space-xl:600px; --oi-block-space-xxl:600px\"><\/div>\n<\/div>\n\n<\/div>\n\n<div class=\"oi-block oi-block-layout-row-column col-1 col-sm-1 col-md-1 col-lg-1 col-xl-1 col-xxl-1\" style=\"\" >\n    <div class=\"oi-block oi-block-layout-space\" style=\"--oi-block-space-xs:1px; --oi-block-space-sm:1px; --oi-block-space-md:1px; --oi-block-space-lg:30px; --oi-block-space-xl:30px; --oi-block-space-xxl:30px\"><\/div>\n\n<\/div>\n\n<div class=\"oi-block oi-block-layout-row-column col-12 col-sm-12 col-md-12 col-lg-4 col-xl-4 col-xxl-4\" style=\"\" >\n\n<div class=\"wp-block-group has-custom-sizing is-layout-constrained wp-block-group-is-layout-constrained\" style=\"--oi-style-padding-xs:50px 50px 50px 50px;--oi-style-padding-sm:50px 50px 50px 50px;--oi-style-padding-md:100px 100px 100px 100px\">\n<h3 class=\"wp-block-heading\">D\u00e9couvrez la nouvelle machine de trempe TM120-MAX<\/h3>\n\n\n\n<p>Observez le fonctionnement de la machine et d\u00e9couvrez comment fonctionne la nouvelle temp\u00e9reuse de chocolat industriel en continu de Mia Food Tech.<\/p>\n\n\n<div class=\"oi-block oi-block-layout-button\" ><a href=\"https:\/\/miaft.com\/fr\/product\/temperatrice-cioccolato-120-kg-max\/#video\" title=\"\" class=\"btn btn-default btn-type-default \" >\n    REGARDER LA VID\u00c9O    <\/a><\/div><\/div>\n\n<\/div>\n    <\/div>\n<\/div>\n\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":-1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"MIA Food Tech - Attrezzature per l'industria dolciaria","_seopress_titles_desc":"La MIA Food Tech realizza macchine dedicate al settore alimentare con speciale attenzione per prodotti del settore dolciario.","_seopress_robots_index":"","fixed_header":true,"header_theme":"light","reserved_page_description":"","footnotes":""},"class_list":["post-59","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/miaft.com\/fr\/wp-json\/wp\/v2\/pages\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miaft.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/miaft.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/miaft.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/miaft.com\/fr\/wp-json\/wp\/v2\/comments?post=59"}],"version-history":[{"count":107,"href":"https:\/\/miaft.com\/fr\/wp-json\/wp\/v2\/pages\/59\/revisions"}],"predecessor-version":[{"id":37782,"href":"https:\/\/miaft.com\/fr\/wp-json\/wp\/v2\/pages\/59\/revisions\/37782"}],"wp:attachment":[{"href":"https:\/\/miaft.com\/fr\/wp-json\/wp\/v2\/media?parent=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}